{"id":6223,"date":"2021-07-27T15:32:25","date_gmt":"2021-07-27T14:32:25","guid":{"rendered":"https:\/\/www.operationalgroup.com\/?page_id=6223"},"modified":"2025-12-03T14:29:19","modified_gmt":"2025-12-03T14:29:19","slug":"optimisation-energetique","status":"publish","type":"page","link":"https:\/\/www.operationalgroup.com\/fr\/optimisation-energetique\/","title":{"rendered":"Optimisation \u00e9nerg\u00e9tique"},"content":{"rendered":"<p>Operational Group est un acteur majeur dans le domaine de l&rsquo;optimisation \u00e9nerg\u00e9tique des s\u00e9cheurs et des proc\u00e9d\u00e9s industriels. Nous apportons des solutions intelligentes et relevons les d\u00e9fis de nos clients dans le domaine de l&rsquo;efficacit\u00e9 de production, de l&rsquo;optimisation \u00e9nerg\u00e9tique et des aspects environnementaux.<\/p>\n<p>Nous am\u00e9liorons la conception de votre s\u00e9choir industriel afin d&rsquo;\u00e9liminer les solvants et l&rsquo;humidit\u00e9 issus du s\u00e9chage, tout en respectant vos contraintes et les exigences environnementales.<\/p>\n<p>Des am\u00e9liorations tr\u00e8s efficaces augmentent les vitesses de productions et la qualit\u00e9 des produits tout en particulier les consommations d&rsquo;\u00e9nergie et les \u00e9missions de gaz contribuant \u00e0 la pollution atmosph\u00e9rique.<\/p>\n<p>Nous r\u00e9duisons vos co\u00fbts, am\u00e9liorons votre empreinte carbone et faisons un pas de plus vers le \u00ab d\u00e9veloppement durable des entreprises \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operational Group est un acteur majeur dans le domaine de l&rsquo;optimisation \u00e9nerg\u00e9tique des s\u00e9cheurs et des proc\u00e9d\u00e9s industriels. Nous apportons&#8230;<\/p>\n","protected":false},"author":24,"featured_media":3340,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-solution-landing.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-6223","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/pages\/6223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/comments?post=6223"}],"version-history":[{"count":6,"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/pages\/6223\/revisions"}],"predecessor-version":[{"id":11646,"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/pages\/6223\/revisions\/11646"}],"wp:attachment":[{"href":"https:\/\/www.operationalgroup.com\/fr\/wp-json\/wp\/v2\/media?parent=6223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}